{"id":3832,"date":"2021-06-02T20:43:27","date_gmt":"2021-06-02T20:43:27","guid":{"rendered":"http:\/\/localhost\/import\/product\/5er-pokalserie-pokale-golden-supreme-ab-305-cm\/"},"modified":"2024-01-03T14:01:45","modified_gmt":"2024-01-03T14:01:45","slug":"5er-pokalserie-pokale-golden-supreme-ab-305-cm","status":"publish","type":"product","link":"https:\/\/pokale.shop\/ps\/product\/5er-pokalserie-pokale-golden-supreme-ab-305-cm\/","title":{"rendered":"5er Pokalserie Pokale GOLDEN SUPREME ab 30,5 cm"},"content":{"rendered":"<p>Mit unseren GOLDEN SUPREME Pokalen wird Ihre Siegerehrung zum absoluten Highlight !<br \/>\nEs sind Pokale f\u00fcr ganz besondere Auszeichnungen und Events zu einem Top Preis.<\/p>\n<p>Diese Pokale sind der Blickfang bei jeder Siegerehrung und der Garant f\u00fcr eine erfolgreiche Veranstaltung.<\/p>\n<p>Sie erhalten <b>5 Pokale<\/b> in folgenden Gr\u00f6\u00dfen:<br \/>\n1 x Pokal (H\u00f6he: 30,5 cm &#8211; Durchmesser: 8 cm)<\/p>\n<p>1 x Pokal (H\u00f6he: 31,5 cm &#8211; Durchmesser: 8 cm )<\/p>\n<p>1 x Pokal (H\u00f6he: 32 cm &#8211; Durchmesser: 8 cm)<\/p>\n<p>1 x Pokal (H\u00f6he: 34 cm &#8211; Durchmesser: 10 cm )<\/p>\n<p>1 x Pokal (H\u00f6he: 34,5 cm &#8211; Durchmesser: 10 cm)<\/p>\n<p>Selbstverst\u00e4ndlich ist im Preis bereits die Gravur und das Emblem je Pokal enthalten.<br \/>\nGeben Sie hierzu einfach Ihren gew\u00fcnschten Gravurtext f\u00fcr alle Pokale in das Textfeld ein.<\/p>\n<p><b>Bitte beachten Sie &#8211; f\u00fcr das Gravurschild stehen Ihnen 3 Zeilen zur Verf\u00fcgung &#8211; pro Zeile max. 30 Zeichen inkl. Leerzeichen. <\/b><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit unseren GOLDEN SUPREME Pokalen wird Ihre Siegerehrung zum absoluten Highlight ! Es sind Pokale f\u00fcr ganz besondere Auszeichnungen und Events zu einem Top Preis. Diese Pokale sind der Blickfang bei jeder Siegerehrung und der Garant f\u00fcr eine erfolgreiche Veranstaltung. Sie erhalten 5 Pokale in folgenden Gr\u00f6\u00dfen: 1 x Pokal&hellip;<\/p>\n","protected":false},"featured_media":3833,"comment_status":"open","ping_status":"closed","template":"","meta":{"spay_email":""},"product_cat":[16,17,20],"product_tag":[],"class_list":["post-3832","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-pokale","product_cat-pokale-pokale","product_cat-5er-pokale-serie"],"_links":{"self":[{"href":"https:\/\/pokale.shop\/ps\/wp-json\/wp\/v2\/product\/3832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pokale.shop\/ps\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pokale.shop\/ps\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/pokale.shop\/ps\/wp-json\/wp\/v2\/comments?post=3832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pokale.shop\/ps\/wp-json\/wp\/v2\/media\/3833"}],"wp:attachment":[{"href":"https:\/\/pokale.shop\/ps\/wp-json\/wp\/v2\/media?parent=3832"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pokale.shop\/ps\/wp-json\/wp\/v2\/product_cat?post=3832"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pokale.shop\/ps\/wp-json\/wp\/v2\/product_tag?post=3832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}